{"id":86238,"date":"2020-09-07T11:58:16","date_gmt":"2020-09-07T11:58:16","guid":{"rendered":"https:\/\/www.demac.it\/cable-reel-for-digital-signals\/"},"modified":"2020-11-06T08:34:32","modified_gmt":"2020-11-06T08:34:32","slug":"%e6%95%b0%e5%ad%97%e4%bf%a1%e5%8f%b7%e7%94%b5%e7%bc%86","status":"publish","type":"post","link":"https:\/\/www.demac.it\/zh-hant\/%e6%95%b0%e5%ad%97%e4%bf%a1%e5%8f%b7%e7%94%b5%e7%bc%86\/","title":{"rendered":"\u6570\u5b57\u4fe1\u53f7\u7535\u7f06"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<hr \/>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;86239&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1589452632201{margin-top: 10px !important;}&#8221; col_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221;][vc_column_text]<strong>\u7279\u5f81<\/strong><\/p>\n<ul>\n<li>\u5f39\u7c27\u81ea\u52a8\u7ed5\u7ebf<\/li>\n<li>\u8bbe\u8ba1\u7d27\u51d1<\/li>\n<li>\u7535\u7f06\u957f\u5ea6\uff1a6m<\/li>\n<li>CANBus, \u4ee5\u592a\u7f51\u548c\u6240\u6709\u6570\u5b57\u4fe1\u53f7\u7c7b\u578b<\/li>\n<li>\u5c4f\u853d\u7535\u7f06<\/li>\n<li>IP66 \u9632\u62a4\u7b49\u7ea7<\/li>\n<\/ul>\n<hr \/>\n<p><strong>\u6280\u672f\u6307\u6807<\/strong><\/p>\n<ul>\n<li><strong>\u578b\u53f7<\/strong>: CR 180.041406<\/li>\n<li><strong>\u7535\u7f06<\/strong>: 4\u00d70.14 mm2<\/li>\n<li><strong>\u7535\u538b<\/strong>: 50V<\/li>\n<li><strong>\u7535\u6d41<\/strong>: 2 A<\/li>\n<li><strong>\u9632\u62a4\u7b49\u7ea7:<\/strong> IP 66<\/li>\n<li><strong>\u7535\u7f06\u5de5\u4f5c\u957f\u5ea6<\/strong>: 6m<\/li>\n<\/ul>\n<p>[\/vc_column_text]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"30\" data-normal_resolution=\"1024\" data-normal_size=\"\" data-tablet_resolution=\"800\" data-tablet_size=\"\" data-mobile_resolution=\"480\" data-mobile_size=\"\" style=\"height: 30px;\"><\/div><div id=\"dfd-button-6a56dc958421a\" class=\"dfd-button-module-wrap dfd-button-6a56dc958421a\"><div class=\"dfd-button-module  style_2 text-left dfd-horizontal dfd-top-to-bottom dfd-button-icon-left dfd-button-icon-hover-simple\" ><a href=\"https:\/\/www.demac.it\/wp-content\/uploads\/2020\/09\/nws_44.pdf\" target=\"_blank\" class=\"dfd-button-link\"><span class=\"dfd-button-inner-cover\"><span class=\"dfd-button-text-main\"><i class=\"dfd-icon-document\"><\/i>\u6280\u8853\u8868<\/span><\/span><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {$(\"head\").append(\"<style>#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover span i, .dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover span i {font-size: 20px;}#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main {color: #ffffff}#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-border-decoration,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover {border-radius:2px;}#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:before,#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:after,#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module.style_6 .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:before,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:after,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module.style_6 .dfd-button-link .dfd-button-inner-cover .dfd-button-text-main {background: #1b1b1b;border-style:solid;border-width:1px;border-radius:2px;border-color:#1b1b1b;}#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module:not(.style_6) .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main,#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module:not(.style_6) .dfd-button-link:hover .dfd-button-inner-cover .dfd-button-text-main,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover {color: #ffffff;}#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-border-decoration,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link:hover .dfd-button-inner-cover {border-radius:2px;}#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:after,#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:before,#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover .dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module:not(.style_4) .dfd-button-link .dfd-button-inner-cover:after,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link .dfd-button-inner-cover:before,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module .dfd-button-link .dfd-button-inner-cover .dfd-button-text-hover {background: #ad2e27;border-style:solid;border-width:1px;border-radius:2px;border-color:#ad2e27;}#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module.style_3 .dfd-button-link:hover .dfd-button-inner-cover:before,#dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link:hover .dfd-button-inner-cover:before,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module.style_3 .dfd-button-link:hover .dfd-button-inner-cover:before,.dfd-button-6a56dc958421a.dfd-button-module-wrap .dfd-button-module.style_4 .dfd-button-link:hover .dfd-button-inner-cover:before {border-style:solid;border-width:1px;border-radius:2px;border-color:#ad2e27;}<\/style>\")\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_<\/p>\n","protected":false},"author":1,"featured_media":86239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[234],"tags":[],"class_list":["post-86238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-234"],"_links":{"self":[{"href":"https:\/\/www.demac.it\/zh-hant\/wp-json\/wp\/v2\/posts\/86238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.demac.it\/zh-hant\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.demac.it\/zh-hant\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.demac.it\/zh-hant\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.demac.it\/zh-hant\/wp-json\/wp\/v2\/comments?post=86238"}],"version-history":[{"count":5,"href":"https:\/\/www.demac.it\/zh-hant\/wp-json\/wp\/v2\/posts\/86238\/revisions"}],"predecessor-version":[{"id":86480,"href":"https:\/\/www.demac.it\/zh-hant\/wp-json\/wp\/v2\/posts\/86238\/revisions\/86480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.demac.it\/zh-hant\/wp-json\/wp\/v2\/media\/86239"}],"wp:attachment":[{"href":"https:\/\/www.demac.it\/zh-hant\/wp-json\/wp\/v2\/media?parent=86238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.demac.it\/zh-hant\/wp-json\/wp\/v2\/categories?post=86238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.demac.it\/zh-hant\/wp-json\/wp\/v2\/tags?post=86238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}